{"id":14836,"date":"2021-09-12T09:53:15","date_gmt":"2021-09-12T07:53:15","guid":{"rendered":"https:\/\/xchpool.org\/oui-chia-v1-1-4-bientot-disponible\/"},"modified":"2021-09-12T09:53:49","modified_gmt":"2021-09-12T07:53:49","slug":"oui-chia-v1-1-4-bientot-disponible","status":"publish","type":"post","link":"https:\/\/xchpool.org\/fr\/oui-chia-v1-1-4-bientot-disponible\/","title":{"rendered":"Oui! Chia v1.1.4 bient\u00f4t disponible\u00a0!"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Bonne nouvelle\u00a0! Nous devrions pouvoir commencer \u00e0 cr\u00e9er des plots pour le chia<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Bonjour l&rsquo;\u00e9quipe! Avec la sortie de Chia 1.1.4 pr\u00e9vue cette semaine, nous devrions pouvoir commencer \u00e0 tracer nos parcelles de pooling quelques semaines avant la sortie du pooling ! vous n&rsquo;aurez besoin de tracer vos parcelles de mise en commun qu&rsquo;une seule fois, car vous pourrez ensuite les d\u00e9placer entre les pool en utilisant le protocole de pool unique de chia !<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Pour tous les l\u00e8ve-t\u00f4t Chia\u00a0!<\/strong> Tout le monde re\u00e7oit 0\u00a0% de <strong>CHIA POOL FEE<\/strong> pour les 3 premiers mois. Apr\u00e8s ces 3 mois, vous b\u00e9n\u00e9ficierez d&rsquo;une<strong> remise \u00e0 vie .<\/strong><\/p><p><em>* Lorsque <a href=\"file:\/\/\/%3fpage_id=4917\">rejoindre le r\u00e9seau chia XCHPool<\/a> dans les 2 premi\u00e8res semaines apr\u00e8s le lancement\u00a0!<\/em><\/p><\/blockquote>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.chia.net\/nl\/releases\/\">Toutes les versions Chia blockchain\u00a0\u00bb<\/a><br\/><a href=\"https:\/\/www.chia.net\/nl \/releases\/\">chia.net\u00a0\u00bb<\/a><\/p>\n\n<hr class=\"wp-block-separator\"\/>\n\n<h4 class=\"has-text-align-center wp-block-heading\">Questions<\/h4>\n\n<h6 class=\"has-text-align-center wp-block-heading\">1. Puis-je faire des plots pour la mise en commun<\/h6>\n\n<p class=\"has-text-align-center wp-block-paragraph\">Non, vous devrez attendre avec chia plotting jusqu&rsquo;\u00e0 ce que l&rsquo;\u00e9quipe de d\u00e9veloppement chia publie le logiciel, dont la sortie est pr\u00e9vue fin mai.<\/p>\n\n<h6 class=\"has-text-align-center wp-block-heading\">3. Comment puis-je rejoindre votre pool ?<\/h6>\n\n<p class=\"has-text-align-center wp-block-paragraph\">La mise en commun n&rsquo;est pas encore disponible, vous ne pouvez donc pas. Nous visons \u00e0 \u00eatre mis en ligne le jour o\u00f9 la mise en commun sera officiellement publi\u00e9e par l&rsquo;\u00e9quipe chia. Pour l&rsquo;instant, vous pouvez vous inscrire \u00e0 notre liste de diffusion, nous suivre sur Twitter ou par t\u00e9l\u00e9gramme, et nous vous enverrons un message d\u00e8s que vous pourrez nous rejoindre ! nous vous enverrons \u00e9galement un petit guide avec des \u00e9tapes tr\u00e8s simples sur la fa\u00e7on de rejoindre la pool ! <strong><a href=\"https:\/\/xchpool.org\/faq\/\">Toutes les FAQ<\/a><\/strong><\/p>\n\n<p class=\"has-text-align-center wp-block-paragraph\"><\/p>\n\n<hr class=\"wp-block-separator\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Bonne nouvelle\u00a0! Nous devrions pouvoir commencer \u00e0 cr\u00e9er des plots pour le chia Bonjour l&rsquo;\u00e9quipe! Avec la sortie de Chia 1.1.4 pr\u00e9vue cette semaine, nous devrions pouvoir commencer \u00e0 tracer nos parcelles de pooling quelques semaines avant la sortie du pooling ! vous n&rsquo;aurez besoin de tracer vos parcelles de mise en commun qu&rsquo;une seule [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":14842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-14836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/posts\/14836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/comments?post=14836"}],"version-history":[{"count":0,"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/posts\/14836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/media\/14842"}],"wp:attachment":[{"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/media?parent=14836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/categories?post=14836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xchpool.org\/fr\/wp-json\/wp\/v2\/tags?post=14836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}